{"id":9628,"date":"2017-11-02T05:07:37","date_gmt":"2017-11-02T05:07:37","guid":{"rendered":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg"},"modified":"2017-11-02T05:07:37","modified_gmt":"2017-11-02T05:07:37","slug":"7103","status":"inherit","type":"attachment","link":"https:\/\/www.its.ac.id\/news\/serunya-nonton-piala-dunia-bareng-upt-mik\/attachment\/7103\/","title":{"rendered":"7103"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-9628","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7103 - ITS News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7103 - ITS News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"ITS News\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"213\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg\",\"url\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg\",\"name\":\"7103 - ITS News\",\"isPartOf\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/#website\"},\"datePublished\":\"2017-11-02T05:07:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.its.ac.id\/news\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serunya Nonton Piala Dunia Bareng UPT MIK\",\"item\":\"https:\/\/www.its.ac.id\/news\/serunya-nonton-piala-dunia-bareng-upt-mik\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"7103\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.its.ac.id\/news\/#website\",\"url\":\"https:\/\/www.its.ac.id\/news\/\",\"name\":\"ITS News\",\"description\":\"Institut Teknologi Sepuluh Nopember\",\"publisher\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.its.ac.id\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.its.ac.id\/news\/#organization\",\"name\":\"ITS News\",\"url\":\"https:\/\/www.its.ac.id\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg\",\"contentUrl\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg\",\"width\":98,\"height\":56,\"caption\":\"ITS News\"},\"image\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7103 - ITS News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg","og_locale":"en_US","og_type":"article","og_title":"7103 - ITS News","og_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg","og_site_name":"ITS News","og_image":[{"width":213,"height":160,"url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg","url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg","name":"7103 - ITS News","isPartOf":{"@id":"https:\/\/www.its.ac.id\/news\/#website"},"datePublished":"2017-11-02T05:07:37+00:00","breadcrumb":{"@id":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.its.ac.id\/news\/en\/"},{"@type":"ListItem","position":2,"name":"Serunya Nonton Piala Dunia Bareng UPT MIK","item":"https:\/\/www.its.ac.id\/news\/serunya-nonton-piala-dunia-bareng-upt-mik\/"},{"@type":"ListItem","position":3,"name":"7103"}]},{"@type":"WebSite","@id":"https:\/\/www.its.ac.id\/news\/#website","url":"https:\/\/www.its.ac.id\/news\/","name":"ITS News","description":"Institut Teknologi Sepuluh Nopember","publisher":{"@id":"https:\/\/www.its.ac.id\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.its.ac.id\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.its.ac.id\/news\/#organization","name":"ITS News","url":"https:\/\/www.its.ac.id\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg","contentUrl":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg","width":98,"height":56,"caption":"ITS News"},"image":{"@id":"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/"}}]}},"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg'><img decoding=\"async\" width=\"213\" height=\"160\" src=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":213,"height":160,"file":"2017\/11\/7103.jpeg","sizes":{"thumbnail":{"file":"7103-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103-150x150.jpeg"},"full":{"file":"7103.jpeg","width":213,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"optimus":{"profit":"8","quantity":100,"webp":0}},"post":9627,"source_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/7103.jpeg","_links":{"self":[{"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/media\/9628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/comments?post=9628"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":9627,"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/posts\/9627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}