{"id":6932,"date":"2017-11-02T04:58:21","date_gmt":"2017-11-02T04:58:21","guid":{"rendered":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg"},"modified":"2017-11-02T04:58:21","modified_gmt":"2017-11-02T04:58:21","slug":"4972","status":"inherit","type":"attachment","link":"https:\/\/www.its.ac.id\/news\/merger-upt-pusat-bahasa-dengan-cultural-centre\/attachment\/4972\/","title":{"rendered":"4972"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-6932","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4972 - ITS News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4972 - ITS News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"ITS News\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"220\" \/>\n\t<meta property=\"og:image:height\" content=\"146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg\",\"url\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg\",\"name\":\"4972 - ITS News\",\"isPartOf\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/#website\"},\"datePublished\":\"2017-11-02T04:58:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.its.ac.id\/news\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Merger UPT Pusat Bahasa Dengan Cultural Centre\",\"item\":\"https:\/\/www.its.ac.id\/news\/merger-upt-pusat-bahasa-dengan-cultural-centre\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4972\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.its.ac.id\/news\/#website\",\"url\":\"https:\/\/www.its.ac.id\/news\/\",\"name\":\"ITS News\",\"description\":\"Institut Teknologi Sepuluh Nopember\",\"publisher\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.its.ac.id\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.its.ac.id\/news\/#organization\",\"name\":\"ITS News\",\"url\":\"https:\/\/www.its.ac.id\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg\",\"contentUrl\":\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg\",\"width\":98,\"height\":56,\"caption\":\"ITS News\"},\"image\":{\"@id\":\"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4972 - ITS News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg","og_locale":"en_US","og_type":"article","og_title":"4972 - ITS News","og_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg","og_site_name":"ITS News","og_image":[{"width":220,"height":146,"url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg","url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg","name":"4972 - ITS News","isPartOf":{"@id":"https:\/\/www.its.ac.id\/news\/#website"},"datePublished":"2017-11-02T04:58:21+00:00","breadcrumb":{"@id":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.its.ac.id\/news\/en\/"},{"@type":"ListItem","position":2,"name":"Merger UPT Pusat Bahasa Dengan Cultural Centre","item":"https:\/\/www.its.ac.id\/news\/merger-upt-pusat-bahasa-dengan-cultural-centre\/"},{"@type":"ListItem","position":3,"name":"4972"}]},{"@type":"WebSite","@id":"https:\/\/www.its.ac.id\/news\/#website","url":"https:\/\/www.its.ac.id\/news\/","name":"ITS News","description":"Institut Teknologi Sepuluh Nopember","publisher":{"@id":"https:\/\/www.its.ac.id\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.its.ac.id\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.its.ac.id\/news\/#organization","name":"ITS News","url":"https:\/\/www.its.ac.id\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg","contentUrl":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-ITS.svg","width":98,"height":56,"caption":"ITS News"},"image":{"@id":"https:\/\/www.its.ac.id\/news\/#\/schema\/logo\/image\/"}}]}},"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg'><img decoding=\"async\" width=\"220\" height=\"146\" src=\"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":220,"height":146,"file":"2017\/11\/4972.jpeg","sizes":{"thumbnail":{"file":"4972-150x146.jpeg","width":150,"height":146,"mime_type":"image\/jpeg","source_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972-150x146.jpeg"},"full":{"file":"4972.jpeg","width":220,"height":146,"mime_type":"image\/jpeg","source_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"optimus":{"profit":"6","quantity":100,"webp":0}},"post":6931,"source_url":"https:\/\/www.its.ac.id\/news\/wp-content\/uploads\/sites\/2\/2017\/11\/4972.jpeg","_links":{"self":[{"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/media\/6932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/comments?post=6932"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6931,"href":"https:\/\/www.its.ac.id\/news\/wp-json\/wp\/v2\/posts\/6931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}